{"id":9373,"date":"2024-04-03T20:29:18","date_gmt":"2024-04-03T20:29:18","guid":{"rendered":"https:\/\/designed4-you.com\/?post_type=product&#038;p=9373"},"modified":"2026-07-21T20:38:43","modified_gmt":"2026-07-21T20:38:43","slug":"rote-und-weisse-tasche-mit-einer-hirschfigur","status":"publish","type":"product","link":"https:\/\/designed4-you.com\/de\/produkt\/rote-und-weisse-tasche-mit-einer-hirschfigur\/","title":{"rendered":"Rote und wei\u00dfe Tasche mit einer Hirschfigur"},"content":{"rendered":"<p>Diese sch\u00f6ne rote Tasche mit einem wei\u00dfen Hirsch und Griff ist sehr elegant und praktisch. Dank eines rechteckigen Bodens steht es aufrecht.<\/p>\n<p>Die Au\u00dfenseite der Tasche besteht aus Polyestergewebe, ist vollst\u00e4ndig mit einem beigen Baumwollstoff gef\u00fcttert und hat einen roten Rei\u00dfverschluss, eine Quaste und einen roten\/wei\u00dfen Griff<\/p>\n<p>Diese Tasche ist einzigartig und handgefertigt in Frankreich, im Departement Moselle, im Grand-Est.<\/p>\n<p>Kann als Handtasche, Reise-Kit oder Tasche Zubeh\u00f6r benutzt werden.<\/p>\n<p>Das ist das perfekte Geschenk f\u00fcr Sie, Ihre Familie oder Ihre Freunde! Es kann mit einer sch\u00f6nen Geldb\u00f6rse kombiniert werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Diese sch\u00f6ne rot-wei\u00dfe Tasche mit einem Griff ist ein einzigartiges Produkt, das auf Upcycling basiert. Es ist handgefertigt in Frankreich, im Departement Moselle, im Grand-Est.<\/p>\n<p>Perfekt als Handtasche, Reiseset oder Taschenzubeh\u00f6r.<\/p>\n<p>Die Abmessungen sind :<\/p>\n<p>Breite: 26 cm + 25,5 cm f\u00fcr den Griff<\/p>\n<p>Tiefe: 8 cm<\/p>\n<p>H\u00f6he: ca. 15,5 cm<\/p>\n<p>Gewicht: 100 g<\/p>\n<p><strong>Material:<\/strong>\u00a0Polyester<\/p>","protected":false},"featured_media":2350,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false},"product_brand":[],"product_cat":[704,708],"product_tag":[],"class_list":["post-9373","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoires-de","product_cat-tasche","pa_material-cotton-en","pa_material-polyester-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/product\/9373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/comments?post=9373"}],"version-history":[{"count":0,"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/product\/9373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/media\/2350"}],"wp:attachment":[{"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/media?parent=9373"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/product_brand?post=9373"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/product_cat?post=9373"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/designed4-you.com\/de\/wp-json\/wp\/v2\/product_tag?post=9373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}